{"id":8411,"date":"2022-08-16T10:23:06","date_gmt":"2022-08-16T10:23:06","guid":{"rendered":"http:\/\/www.jadek-pensa.si\/?p=8411"},"modified":"2022-10-12T12:58:17","modified_gmt":"2022-10-12T12:58:17","slug":"sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet","status":"publish","type":"post","link":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/","title":{"rendered":"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet?"},"content":{"rendered":"<p>Das Verbraucherschutzrecht spielt sowohl auf nationaler Ebene als auch auf der Ebene der Europ\u00e4ischen Union eine wichtige Rolle. Obwohl es durch EU-Richtlinien geregelt wird, die in ihrer Zielsetzung f\u00fcr die Mitgliedstaaten verbindlich sind, l\u00e4sst sich der EU-Gesetzgeber seit vielen Jahren von dem Trend zur so genannten Maximalharmonisierung des Verbraucherrechts leiten. Das Verbraucherschutzrecht in der EU setzt sich damit nicht nur f\u00fcr ein hohes, sondern auch f\u00fcr ein einheitliches Verbraucherschutzniveau in den EU-Mitgliedstaaten ein.<\/p>\n<p>Im Rahmen des sogenannten &#8222;New Deal for Consumers&#8220; wurde im November 2019 auf EU-Ebene eine neue Richtlinie (EU) 2019\/2161 des Europ\u00e4ischen Parlaments und des Rates, auch &#8222;Omnibus-Richtlinie&#8220; genannt, verabschiedet, die das EU-Verbraucherschutzrecht durch \u00c4nderung mehrerer bestehender Richtlinien aktualisiert.\u00a0 Zuvor wurden im Mai 2019 zwei weitere wichtige Richtlinien verabschiedet, n\u00e4mlich die Richtlinie (EU) 2019\/770 des Europ\u00e4ischen Parlaments und des Rates \u00fcber bestimmte Aspekte von Vertr\u00e4gen \u00fcber die Bereitstellung digitaler Inhalte und Dienstleistungen und die Richtlinie (EU) 2019\/771 des Europ\u00e4ischen Parlaments und des Rates \u00fcber bestimmte Aspekte des Verkaufs von Waren, zur \u00c4nderung der Verordnung (EU) 2017\/2394 und der Richtlinie 2009\/22\/EG sowie zur Aufhebung der Richtlinie 1999\/44\/EG.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Gesetzgebungsverfahren befindet sich ein Vorschlag f\u00fcr ein neues Verbraucherschutzgesetz, das einige \u00c4nderungen und Neuerungen mit sich &#8230;<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[186],"class_list":["post-8411","post","type-post","status-publish","format-standard","hentry","category-fachbeitraege","tag-gesetzgebung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet? - Jadek &amp; Pensa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet? - Jadek &amp; Pensa\" \/>\n<meta property=\"og:description\" content=\"Im Gesetzgebungsverfahren befindet sich ein Vorschlag f\u00fcr ein neues Verbraucherschutzgesetz, das einige \u00c4nderungen und Neuerungen mit sich ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/\" \/>\n<meta property=\"og:site_name\" content=\"Jadek &amp; Pensa\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T10:23:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-12T12:58:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jadek-pensa.si\/wp-content\/uploads\/2024\/12\/social-image-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"humanfrog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"humanfrog\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/\"},\"author\":{\"name\":\"humanfrog\",\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#\\\/schema\\\/person\\\/0e5294c4ec0f02ccd8fa506c3bdec5fb\"},\"headline\":\"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet?\",\"datePublished\":\"2022-08-16T10:23:06+00:00\",\"dateModified\":\"2022-10-12T12:58:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/\"},\"wordCount\":189,\"keywords\":[\"Gesetzgebung\"],\"articleSection\":[\"Fachbeitr\u00e4ge\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/\",\"url\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/\",\"name\":\"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet? - Jadek &amp; Pensa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#website\"},\"datePublished\":\"2022-08-16T10:23:06+00:00\",\"dateModified\":\"2022-10-12T12:58:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#\\\/schema\\\/person\\\/0e5294c4ec0f02ccd8fa506c3bdec5fb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/\",\"name\":\"Jadek &amp; Pensa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#\\\/schema\\\/person\\\/0e5294c4ec0f02ccd8fa506c3bdec5fb\",\"name\":\"humanfrog\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/767edaac2e440251f7a8b37cdb1143f0256c8985ef2082d48e648de208efdbfa?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/767edaac2e440251f7a8b37cdb1143f0256c8985ef2082d48e648de208efdbfa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/767edaac2e440251f7a8b37cdb1143f0256c8985ef2082d48e648de208efdbfa?s=96&d=mm&r=g\",\"caption\":\"humanfrog\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet? - Jadek &amp; Pensa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/","og_locale":"de_DE","og_type":"article","og_title":"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet? - Jadek &amp; Pensa","og_description":"Im Gesetzgebungsverfahren befindet sich ein Vorschlag f\u00fcr ein neues Verbraucherschutzgesetz, das einige \u00c4nderungen und Neuerungen mit sich ...","og_url":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/","og_site_name":"Jadek &amp; Pensa","article_published_time":"2022-08-16T10:23:06+00:00","article_modified_time":"2022-10-12T12:58:17+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/jadek-pensa.si\/wp-content\/uploads\/2024\/12\/social-image-scaled.jpg","type":"image\/jpeg"}],"author":"humanfrog","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"humanfrog","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/#article","isPartOf":{"@id":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/"},"author":{"name":"humanfrog","@id":"https:\/\/www.jadek-pensa.si\/de\/#\/schema\/person\/0e5294c4ec0f02ccd8fa506c3bdec5fb"},"headline":"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet?","datePublished":"2022-08-16T10:23:06+00:00","dateModified":"2022-10-12T12:58:17+00:00","mainEntityOfPage":{"@id":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/"},"wordCount":189,"keywords":["Gesetzgebung"],"articleSection":["Fachbeitr\u00e4ge"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/","url":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/","name":"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet? - Jadek &amp; Pensa","isPartOf":{"@id":"https:\/\/www.jadek-pensa.si\/de\/#website"},"datePublished":"2022-08-16T10:23:06+00:00","dateModified":"2022-10-12T12:58:17+00:00","author":{"@id":"https:\/\/www.jadek-pensa.si\/de\/#\/schema\/person\/0e5294c4ec0f02ccd8fa506c3bdec5fb"},"breadcrumb":{"@id":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jadek-pensa.si\/de\/sind-sie-auf-die-neuen-verbraucherschutzvorschriften-vorbereitet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jadek-pensa.si\/de\/"},{"@type":"ListItem","position":2,"name":"Sind Sie auf die neuen Verbraucherschutzvorschriften vorbereitet?"}]},{"@type":"WebSite","@id":"https:\/\/www.jadek-pensa.si\/de\/#website","url":"https:\/\/www.jadek-pensa.si\/de\/","name":"Jadek &amp; Pensa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jadek-pensa.si\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.jadek-pensa.si\/de\/#\/schema\/person\/0e5294c4ec0f02ccd8fa506c3bdec5fb","name":"humanfrog","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/767edaac2e440251f7a8b37cdb1143f0256c8985ef2082d48e648de208efdbfa?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/767edaac2e440251f7a8b37cdb1143f0256c8985ef2082d48e648de208efdbfa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/767edaac2e440251f7a8b37cdb1143f0256c8985ef2082d48e648de208efdbfa?s=96&d=mm&r=g","caption":"humanfrog"}}]}},"_links":{"self":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/posts\/8411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/comments?post=8411"}],"version-history":[{"count":0,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/posts\/8411\/revisions"}],"wp:attachment":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/media?parent=8411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/categories?post=8411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/tags?post=8411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}