{"id":4262,"date":"2019-02-20T11:10:14","date_gmt":"2019-02-20T11:10:14","guid":{"rendered":"http:\/\/www.jadek-pensa.si\/?p=4262"},"modified":"2019-02-21T08:39:23","modified_gmt":"2019-02-21T08:39:23","slug":"wie-man-nachfolgestreitigkeiten-vermeiden-kann","status":"publish","type":"post","link":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/","title":{"rendered":"Wie man Nachfolgestreitigkeiten vermeiden kann"},"content":{"rendered":"<p><strong>Wo soll man anfangen?<\/strong><\/p>\n<p>In seinem Artikel Wird das Erbe Reichtum oder Fluch sein, ver\u00f6ffentlicht in der Oktoberausgabe des Direktor Magazine, riet Mag. Samo Lubej, offen die Nachfolge zu besprechen.<\/p>\n<p>Einfacher Rat, aber das Gespr\u00e4ch \u00fcber die Nachfolge ist oft schwierig und in vielen Familien bleiben Nachfolge und Verm\u00f6gensteilung zu Lebzeiten oder im Todesfall ein Tabu.<\/p>\n<p><strong>Verg\u00e4nglichkeit<\/strong><\/p>\n<p>Diese Gespr\u00e4che sind von Natur aus unangenehm, da die Nachfolge ein Ergebnis der Verg\u00e4nglichkeit ist. Obwohl es f\u00fcr alle unvermeidlich ist, ist es nicht angenehm, \u00fcber Verg\u00e4nglichkeit nachzudenken und noch weniger \u00fcber sie mit Personen zu sprechen, mit denen wir tief emotional verbunden sind.<\/p>\n<p>Da es sich im Grunde genommen um Gespr\u00e4che und Reflexionen handelt, die negative Gef\u00fchle aller Beteiligten implizieren, kommt es oft vor, dass wir nicht einmal an die Nachfolge und noch weniger an das Erbe denken wollen, geschweige denn dar\u00fcber reden. Dies gilt umso mehr, wenn Angst besteht, dass Nachfolge zu Konfliktsituationen in der Familie f\u00fchren wird.<\/p>\n<p>Im ersten Teil dieses Artikels werde ich einige Erfahrungen aus der Praxis beschreiben, als das Erbe zum Fluch wurde, insbesondere in Bezug auf die Beziehungen zwischen den Erben, da es klug ist, aus den Erfahrungen anderer zu lernen. Im Folgenden werde ich darlegen, wie es mit dem richtigen Ansatz und vor allem mit geeigneter Kommunikation m\u00f6glich ist, viele Streitigkeiten und Gerichtsverfahren zu vermeiden, die f\u00fcr alle teuer und anstrengend und vor allem verheerend f\u00fcr die Familienbeziehungen sind.<\/p>\n<p><strong>Langwierige Nachlassverfahren<\/strong><\/p>\n<p>Wie komplex und langwierig ein Nachlassverfahren sein kann, ergibt sich aus dem folgenden realen Beispiel aus der Praxis: Um sein Verm\u00f6gen auf seine drei Kinder und seine Frau aufzuteilen, hat der Verstorbene in gutem Glauben einen Willen gemacht. Er hat sogar festgelegt, dass jedem der Kinder ein junger Stier oder sein Gegenwert zusteht, so dass keines von ihnen benachteiligt wird. Es schien, dass der Verstorbene sorgf\u00e4ltig gehandelt hat und dass seine Nachkommen in der Lage sein werden, das Erbe ohne Probleme zu teilen.<\/p>\n<p>Der Verstorbene starb in den 90er Jahren. Die Nachkommen brieten den ersten Stier zusammen, noch bevor das Erbverfahren \u00fcberhaupt begonnen hat. Im Erbverfahren wurde alles zwischen den Erben umstritten; der Wert des Nachlasses, der Wert der Geschenke und der Wert des jungen Stiers wurden von Gutachtern und Sachverst\u00e4ndigen bewertet, der erste Nachlassbeschluss wurde erst 8 Jahre nach dem Tod des Verstorbenen erlassen und das Erbverfahren wurde erst 20 Jahre sp\u00e4ter endg\u00fcltig abgeschlossen. Zu diesem Zeitpunkt gab es keine Stiere mehr auf dem Hof, und selbst wenn sie es g\u00e4be, w\u00fcrden die Erben sie definitiv nicht mehr zusammen braten.<\/p>\n<p>In diesem Zusammenhang ist auch zu erl\u00e4utern, dass es im beschriebenen Erbverfahren keine solchen Streitigkeiten gab, aufgrund derer das Nachlassgericht einen der Erben an Gerichtsverfahren verweisen w\u00fcrde. Sollte das Verfahren unterbrochen werden und in der Zwischenzeit ein Zivilgericht entscheiden w\u00fcrde, w\u00e4re bis heute nicht bekannt, wie das Verm\u00f6gen auf die Erben verteilt wird.<\/p>\n<p>Im beschriebenen Fall f\u00fchlten sich einige der Erben aufgrund des Willens und der Geschenke, die sie zu Lebzeiten erhielten, benachteiligt. Die Entscheidung in dieser Angelegenheit wurde dem Gericht \u00fcberlassen. Meines Wissens waren am Ende alle von der Entscheidung des Gerichts entt\u00e4uscht.<\/p>\n<p><strong>Unzufriedenheit wegen Missverst\u00e4ndnis des Willens<\/strong><\/p>\n<p>Auch wenn die Erben nicht in langwierige Gerichtsverfahren zur Durchsetzung ihrer Rechte geraten, k\u00f6nnen Testament und Erbschaft dennoch negative Auswirkungen auf ihre gegenseitigen Beziehungen haben. Nach meiner Erfahrung respektieren viele den letzten Willen des Verstorbenen, f\u00fchlen sich aber dennoch benachteiligt. Sie kriegen gew\u00f6hnlich solche Gef\u00fchle, wenn sie die Gr\u00fcnde, warum der Verstorbene beschlossen hat, den Nachlass auf diese Weise aufzuteilen, nicht verstehen oder mit den Erkl\u00e4rungen des Verstorbenen im Testament nicht einverstanden sind.<\/p>\n<p>Oftmals schreiben und speichern die Erblasser ihren Willen so, dass die Erben erst nach ihrem Tod mit dem Inhalt vertraut werden. Vielleicht tun sie das, um Konflikte zu Lebzeiten zu vermeiden. Daher kann es vorkommen, dass die Erben den Willen nicht verstehen oder dass die Aufteilung nicht ihren Interessen entspricht. Sie werden ihren Zorn auf den Verstorbenen auf andere Erben richten, und die Beziehungen zwischen ihnen werden sich verschlechtern.<\/p>\n<p><strong>&#8222;Zusammenarbeit bringt Frustration&#8220;<\/strong><\/p>\n<p>Auch wenn verstorbene Personen keine Entzweiung zwischen den Erben mit dem Testament hervorrufen m\u00f6chten und sich entscheiden, dass sie wie gesetzlich vorgesehen erben sollen (gesetzliche Erbfolge), kommt es in der Praxis immer noch zu Streitigkeiten, die sich negativ auf die Familienbeziehungen auswirken.<\/p>\n<p>Das Hauptmerkmal der gesetzlichen Erbfolge ist, dass der Nachlass durch Erbteilen geteilt wird. Das bedeutet, dass jeder der Erben einen proportionalen Anteil an allen Dingen des Nachlasses erh\u00e4lt: Alle Erben werden zu Miteigent\u00fcmern von Immobilien und auch zu Miteigent\u00fcmern von Aktien, Gesch\u00e4ftsanteilen und anderen Verm\u00f6gen. Die Erben m\u00fcssen dann vereinbaren, wie sie dieses Verm\u00f6gen gemeinsam verwalten werden oder wie sie die Erbschaft mit einer Nachfolgevereinbarung aufteilen sollen. Kommt es nach dem Tod des Verstorbenen zu einem Streit zwischen den Erben, wird das Verm\u00f6gen in der Regel nicht optimal verwaltet, was zu einer Wertminderung f\u00fchrt.<\/p>\n<p>Die Erben k\u00f6nnen zwar eine gerichtliche Trennung beantragen, was wiederum zeitaufwendig ist. Die Aufteilung erfolgt auch nach dem Gesetz, ohne R\u00fccksicht auf die Interessen des Einzelnen.<\/p>\n<p><strong>Vererbung von Gesch\u00e4ftsanteilen<\/strong><\/p>\n<p>In diesem Zusammenhang m\u00f6chte ich auf die Vererbung von Gesch\u00e4ftsanteilen hinweisen. F\u00fcr die Gesch\u00e4ftsanteile sowie f\u00fcr das verbleibende Verm\u00f6gen des Verstorbenen gilt, dass sie zum Zeitpunkt des Todes des Verstorbenen auf die Erben \u00fcbergehen.<\/p>\n<p>Besteht dennoch ein Streit dar\u00fcber, wer der Erbe ist oder was f\u00fcr ein Anteil ein Erbe vererben soll, so kann es vorkommen, dass die Gesellschaft einen aktiven Gesellschafter f\u00fcr die Zeit der L\u00f6sung von Konflikten zwischen den Erben verliert. Wenn wir uns eine Situation vorstellen, in der der Verstorbene auch der Direktor des Unternehmens war, behindert ein solcher Zustand und friert vollst\u00e4ndig den Betrieb des Unternehmens ein.<\/p>\n<p><strong>Gespr\u00e4ch &#8211; Weg zum Verst\u00e4ndnis von W\u00fcnschen<\/strong><\/p>\n<p>Aus allem, was oben gesagt wurde, folgt, dass die Feststellung von Mag. Samo Lubej durchaus stimmt, n\u00e4mlich, dass der gr\u00f6\u00dfte Fehler der Familienf\u00fchrer darin besteht, dass sie einfach nicht \u00fcber die Nachfolge mit anderen Familienmitgliedern sprechen.<\/p>\n<p>Meiner Meinung nach muss man bei den Nachfolgegespr\u00e4chen oft mehr auf die Art der Kommunikation achten als auf den Inhalt der Aufteilung. Ich w\u00fcrde vorschlagen, zun\u00e4chst die Interessen jedes Einzelnen und die Vorstellungen der Nachkommen \u00fcber ihr Leben zu ermitteln und erst dann gemeinsam eine geeignete Art der Aufteilung zu finden.<\/p>\n<p>Stellen wir uns ein Musterbeispiel eines Vaters vor, der eine Orange hat und sie zwischen seinen beiden T\u00f6chtern aufteilen will. Er w\u00fcrde die Orange gerecht in zwei gleiche H\u00e4lften teilen. Trotzdem w\u00e4ren seine beiden T\u00f6chter entt\u00e4uscht, denn die eine wollte das Fleisch der Orange, um daraus Saft zu machen, w\u00e4hrend die andere die Schale wollte, um einen Kuchen zu backen. Durch ein Gespr\u00e4ch und die richtigen Fragen h\u00e4tte der Vater ihre Interessen erkennen und die Orange anders aufteilen k\u00f6nnen.<\/p>\n<p>Um zu erreichen, dass das Verm\u00f6gen weiterhin erfolgreich verwaltet wird und um einen Streit zwischen den Nachfolgern zu vermeiden, m\u00fcssen wir die Interessen der Nachfolger bei der Aufteilung verfolgen und ihre Gef\u00fchle angemessen ber\u00fccksichtigen.<\/p>\n<p><strong>Einbeziehung einer neutralen Person<\/strong><\/p>\n<p>Wenn die Beziehungen zu komplex sind, wenn die Gef\u00fchle zu stark sind und wir nicht in der Lage sind, die Interessen selbst zu erkennen, ist es sinnvoll, eine dritte, neutrale Person in die Gespr\u00e4che einzubeziehen, die das Verfahren strukturiert leitet und eine positive Auswirkung auf die Frage der Erbteilung und die Suche nach einer f\u00fcr alle geeigneten Vereinbarung hat.<\/p>\n<p>In den Familien, in denen die Pflege der Beziehungen viel wichtiger ist als die Aufteilung des Eigentums nach den Regeln des Rechts, ist es meiner Meinung nach angebracht, einen Mediator in die Gespr\u00e4che einzubeziehen. Mediationen werden von verschiedenen Mediationszentren angeboten, darunter das Mediationszentrum der slowenischen Anwaltskammer und auch das so genannte Family Office, das \u00fcber zus\u00e4tzliche Kenntnisse im Bereich der Verm\u00f6gensverwaltung verf\u00fcgt.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artikel ver\u00f6ffentlicht im Direktor Magazine, Nr. 37, Januar 2019&#8230;<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[92],"class_list":["post-4262","post","type-post","status-publish","format-standard","hentry","category-fachbeitraege","tag-vermeidung-und-beilegung-von-rechtsstreitigkeiten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie man Nachfolgestreitigkeiten vermeiden kann - Jadek &amp; Pensa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie man Nachfolgestreitigkeiten vermeiden kann - Jadek &amp; Pensa\" \/>\n<meta property=\"og:description\" content=\"Artikel ver\u00f6ffentlicht im Direktor Magazine, Nr. 37, Januar 2019...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/\" \/>\n<meta property=\"og:site_name\" content=\"Jadek &amp; Pensa\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-20T11:10:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-21T08:39:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jadek-pensa.si\/wp-content\/uploads\/2024\/12\/social-image-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maru\u0161a Lenar\u010di\u010d\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maru\u0161a Lenar\u010di\u010d\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/\"},\"author\":{\"name\":\"Maru\u0161a Lenar\u010di\u010d\",\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#\\\/schema\\\/person\\\/1dc82fb4840bf0a47c9a1b4b953b77dc\"},\"headline\":\"Wie man Nachfolgestreitigkeiten vermeiden kann\",\"datePublished\":\"2019-02-20T11:10:14+00:00\",\"dateModified\":\"2019-02-21T08:39:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/\"},\"wordCount\":1353,\"keywords\":[\"Vermeidung und Beilegung von Rechtsstreitigkeiten\"],\"articleSection\":[\"Fachbeitr\u00e4ge\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/\",\"url\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/\",\"name\":\"Wie man Nachfolgestreitigkeiten vermeiden kann - Jadek &amp; Pensa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#website\"},\"datePublished\":\"2019-02-20T11:10:14+00:00\",\"dateModified\":\"2019-02-21T08:39:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#\\\/schema\\\/person\\\/1dc82fb4840bf0a47c9a1b4b953b77dc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/jadek-pensa.si\\\/de\\\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie man Nachfolgestreitigkeiten vermeiden kann\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/\",\"name\":\"Jadek &amp; Pensa\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.jadek-pensa.si\\\/de\\\/#\\\/schema\\\/person\\\/1dc82fb4840bf0a47c9a1b4b953b77dc\",\"name\":\"Maru\u0161a Lenar\u010di\u010d\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c847d3f5eae2601ecf0a717fc52c11c512efd67344dd7f9eb15f8be375d371?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c847d3f5eae2601ecf0a717fc52c11c512efd67344dd7f9eb15f8be375d371?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c6c847d3f5eae2601ecf0a717fc52c11c512efd67344dd7f9eb15f8be375d371?s=96&d=mm&r=g\",\"caption\":\"Maru\u0161a Lenar\u010di\u010d\"},\"sameAs\":[\"http:\\\/\\\/www.jadek-pensa.si\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie man Nachfolgestreitigkeiten vermeiden kann - Jadek &amp; Pensa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/","og_locale":"de_DE","og_type":"article","og_title":"Wie man Nachfolgestreitigkeiten vermeiden kann - Jadek &amp; Pensa","og_description":"Artikel ver\u00f6ffentlicht im Direktor Magazine, Nr. 37, Januar 2019...","og_url":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/","og_site_name":"Jadek &amp; Pensa","article_published_time":"2019-02-20T11:10:14+00:00","article_modified_time":"2019-02-21T08:39:23+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/jadek-pensa.si\/wp-content\/uploads\/2024\/12\/social-image-scaled.jpg","type":"image\/jpeg"}],"author":"Maru\u0161a Lenar\u010di\u010d","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Maru\u0161a Lenar\u010di\u010d","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/#article","isPartOf":{"@id":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/"},"author":{"name":"Maru\u0161a Lenar\u010di\u010d","@id":"https:\/\/www.jadek-pensa.si\/de\/#\/schema\/person\/1dc82fb4840bf0a47c9a1b4b953b77dc"},"headline":"Wie man Nachfolgestreitigkeiten vermeiden kann","datePublished":"2019-02-20T11:10:14+00:00","dateModified":"2019-02-21T08:39:23+00:00","mainEntityOfPage":{"@id":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/"},"wordCount":1353,"keywords":["Vermeidung und Beilegung von Rechtsstreitigkeiten"],"articleSection":["Fachbeitr\u00e4ge"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/","url":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/","name":"Wie man Nachfolgestreitigkeiten vermeiden kann - Jadek &amp; Pensa","isPartOf":{"@id":"https:\/\/www.jadek-pensa.si\/de\/#website"},"datePublished":"2019-02-20T11:10:14+00:00","dateModified":"2019-02-21T08:39:23+00:00","author":{"@id":"https:\/\/www.jadek-pensa.si\/de\/#\/schema\/person\/1dc82fb4840bf0a47c9a1b4b953b77dc"},"breadcrumb":{"@id":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jadek-pensa.si\/de\/wie-man-nachfolgestreitigkeiten-vermeiden-kann\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.jadek-pensa.si\/de\/"},{"@type":"ListItem","position":2,"name":"Wie man Nachfolgestreitigkeiten vermeiden kann"}]},{"@type":"WebSite","@id":"https:\/\/www.jadek-pensa.si\/de\/#website","url":"https:\/\/www.jadek-pensa.si\/de\/","name":"Jadek &amp; Pensa","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.jadek-pensa.si\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.jadek-pensa.si\/de\/#\/schema\/person\/1dc82fb4840bf0a47c9a1b4b953b77dc","name":"Maru\u0161a Lenar\u010di\u010d","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c6c847d3f5eae2601ecf0a717fc52c11c512efd67344dd7f9eb15f8be375d371?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c6c847d3f5eae2601ecf0a717fc52c11c512efd67344dd7f9eb15f8be375d371?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c6c847d3f5eae2601ecf0a717fc52c11c512efd67344dd7f9eb15f8be375d371?s=96&d=mm&r=g","caption":"Maru\u0161a Lenar\u010di\u010d"},"sameAs":["http:\/\/www.jadek-pensa.si\/"]}]}},"_links":{"self":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/posts\/4262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/comments?post=4262"}],"version-history":[{"count":0,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/posts\/4262\/revisions"}],"wp:attachment":[{"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/media?parent=4262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/categories?post=4262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jadek-pensa.si\/de\/wp-json\/wp\/v2\/tags?post=4262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}